{"id":32388,"date":"2026-07-14T19:32:00","date_gmt":"2026-07-14T22:32:00","guid":{"rendered":"https:\/\/elprofesional.uy\/www\/?p=32388"},"modified":"2026-07-14T19:32:01","modified_gmt":"2026-07-14T22:32:01","slug":"rigen-categorias","status":"publish","type":"post","link":"https:\/\/elprofesional.uy\/www\/archivos\/32388","title":{"rendered":"Rigen categor\u00edas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Aumento de salarios para dom\u00e9sticas se percibir\u00e1 en agosto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el 1 de julio pasado rigen los incrementos en los salarios de las trabajadoras del sector dom\u00e9stico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el convenio firmado en los Consejos de Salarios, las remuneraciones se establecer\u00e1n tambi\u00e9n de acuerdo a las categor\u00edas que, seg\u00fan inform\u00e1ramos oportunamente en <strong>EL PROFESIONAL Diario, <\/strong>tambi\u00e9n est\u00e1n vigentes desde el primer d\u00eda del mes en curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cA partir del 1 de julio est\u00e1 rigiendo un incremento salarial. En la primera franja es de un 2.8% de aumento\u201d <\/strong>anunci\u00f3 la Presidenta del Sindicato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta primera franja, hasta 2025, comprend\u00eda a las trabajadoras que percib\u00edan un salario de $ 35.700.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cPara la segunda franja, para quienes superen los 37.700 Pesos, ser\u00e1 del 1.9% el aumento\u201d <\/strong>inform\u00f3 <strong>Laura Rivero.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cPor lo general, para el interior del pa\u00eds la base ser\u00e1 el salario m\u00ednimo, por lo tanto, el incremento ser\u00e1 del 2.8%\u201d <\/strong>remarc\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los departamentos de Montevideo, Canelones y Maldonado es donde hay m\u00e1s diferenciaci\u00f3n salarial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a las remuneraciones por categor\u00edas, las diferencias no son muy grandes seg\u00fan inform\u00f3 la dirigente sindical. <strong>\u201cHemos le\u00eddo y escuchado un mont\u00f3n de cosas como que vamos a perder un mont\u00f3n de puestos de trabajo. Eso no es as\u00ed\u201d <\/strong>asegur\u00f3. <strong>\u201cTampoco vamos a cobrar tres sueldos por hacer tres categor\u00edas. Ese es un disparate que salieron a decir algunos empleadores por ah\u00ed\u201d <\/strong>agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cEste cambio es solamente para diferenciar las categor\u00edas que hacemos, para no seguir haciendo 4 o 5 cosas al mismo tiempo sin ning\u00fan tipo de diferenciaci\u00f3n salarial\u201d <\/strong>subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cEl salario m\u00ednimo que hasta el 30 de junio estaba en $ 31.178, esa es la categor\u00eda general lo que equivale a $ 134 la hora\u201d <\/strong>revel\u00f3. <strong>\u201cEse era el salario m\u00ednimo y la categor\u00eda general. A partir de ah\u00ed, la de cocina es de $ 32.875 con un valor hora de $ 173. Finalmente, la categor\u00eda de cuidados ser\u00e1 de $ 33.935 y 178.5 la hora\u201d <\/strong>inform\u00f3 Rivero. <strong>\u201cEstos eran los salarios que estaban hasta el 30 de junio\u201d <\/strong>aclar\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cComo a partir del 1 de julio comenzaron a regir las categor\u00edas, obviamente que con el 2.8% se incrementan, entonces los salarios comienzan con la categor\u00eda general en 32.051 Pesos o 168.6 Pesos la hora, la categor\u00eda de cocina $ 33.796 o $ 177.7 por hora y la categor\u00eda de cuidados $ 34.885 o $ 183.5 la hora\u201d <\/strong>adelant\u00f3 en relaci\u00f3n a los salarios que deber\u00e1n percibir las trabajadoras del sector a partir del pasado 1 de julio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cNosotros estamos tratando de hacer todo lo posible, con nuestra manera, para pasarle a las compa\u00f1eras explic\u00e1ndoles c\u00f3mo son las cosas para que se entienda lo mejor posible\u201d <\/strong>sostuvo Laura Rivero&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SEMINARIO EN MELO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el Sindicato \u00danico Nacional de Trabajadoras Dom\u00e9sticas confirmaron a <strong>EL PROFESIONAL Diario <\/strong>que, en el mes de agosto, en fecha a determinar, se realizar\u00e1 en la capital de Cerro Largo un importante Seminario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estar\u00e1n presentes dirigentes nacionales, representantes de la Liga de Amas de Casa, del Ministerio de Trabajo y Seguridad Social y del PIT CNT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paralelamente se har\u00e1 la presentaci\u00f3n de un libro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que el 19 del mes pr\u00f3ximo se celebra el d\u00eda nacional del trabajador dom\u00e9stico que es feriado no laborable pago para todos quienes desempe\u00f1en funciones den el sector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumento de salarios para dom\u00e9sticas se percibir\u00e1 en agosto Desde el 1 de julio pasado rigen los incrementos en los salarios de las trabajadoras del sector dom\u00e9stico. Seg\u00fan el convenio firmado en los Consejos de Salarios, las remuneraciones se establecer\u00e1n tambi\u00e9n de acuerdo a las categor\u00edas que, seg\u00fan inform\u00e1ramos oportunamente en EL PROFESIONAL Diario, tambi\u00e9n &hellip;<\/p>\n","protected":false},"author":3,"featured_media":32395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,18,17,2,31,1,14],"tags":[],"class_list":["post-32388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-locales","category-nacionales","category-politica","category-rio-branco","category-sociales","category-tiempo-libre"],"_links":{"self":[{"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/posts\/32388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/comments?post=32388"}],"version-history":[{"count":1,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/posts\/32388\/revisions"}],"predecessor-version":[{"id":32396,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/posts\/32388\/revisions\/32396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/media\/32395"}],"wp:attachment":[{"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/media?parent=32388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/categories?post=32388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elprofesional.uy\/www\/wp-json\/wp\/v2\/tags?post=32388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}